{"id":280,"count":1,"description":"","link":"https:\/\/moodbooster.de\/en\/product-category\/leinen\/","name":"","slug":"leinen","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archive - Moodbooster<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/moodbooster.de\/product-category\/leinen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archive - Moodbooster\" \/>\n<meta property=\"og:url\" content=\"https:\/\/moodbooster.de\/product-category\/leinen\/\" \/>\n<meta property=\"og:site_name\" content=\"Moodbooster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/moodbooster.de\/product-category\/leinen\/\",\"url\":\"https:\/\/moodbooster.de\/product-category\/leinen\/\",\"name\":\"Archive - Moodbooster\",\"isPartOf\":{\"@id\":\"https:\/\/moodbooster.de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/moodbooster.de\/product-category\/leinen\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/moodbooster.de\/product-category\/leinen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/moodbooster.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leinen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/moodbooster.de\/#website\",\"url\":\"https:\/\/moodbooster.de\/\",\"name\":\"Moodbooster\",\"description\":\"Scented candles for friends, travels and good mood.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/moodbooster.de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archive - Moodbooster","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/moodbooster.de\/product-category\/leinen\/","og_locale":"en_US","og_type":"article","og_title":"Archive - Moodbooster","og_url":"https:\/\/moodbooster.de\/product-category\/leinen\/","og_site_name":"Moodbooster","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/moodbooster.de\/product-category\/leinen\/","url":"https:\/\/moodbooster.de\/product-category\/leinen\/","name":"Archive - Moodbooster","isPartOf":{"@id":"https:\/\/moodbooster.de\/#website"},"breadcrumb":{"@id":"https:\/\/moodbooster.de\/product-category\/leinen\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/moodbooster.de\/product-category\/leinen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/moodbooster.de\/"},{"@type":"ListItem","position":2,"name":"Leinen"}]},{"@type":"WebSite","@id":"https:\/\/moodbooster.de\/#website","url":"https:\/\/moodbooster.de\/","name":"Moodbooster","description":"Scented candles for friends, travels and good mood.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/moodbooster.de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/moodbooster.de\/en\/wp-json\/wp\/v2\/product_cat\/280"}],"collection":[{"href":"https:\/\/moodbooster.de\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/moodbooster.de\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/moodbooster.de\/en\/wp-json\/wp\/v2\/product?product_cat=280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}